{"id":1604,"date":"2026-05-09T10:19:36","date_gmt":"2026-05-09T08:19:36","guid":{"rendered":"https:\/\/lumovape.de\/?page_id=1604"},"modified":"2026-05-09T10:19:37","modified_gmt":"2026-05-09T08:19:37","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"https:\/\/lumovape.de\/fr\/datenschutzerklaerung\/","title":{"rendered":"D\u00e9claration de confidentialit\u00e9"},"content":{"rendered":"<div class=\"wp-block-wd-divider wd-style-line wd-b360b112\"><\/div>\n\n\n\n<h1 class=\"wp-block-wd-title title wd-b4d06891\">D\u00e9claration de confidentialit\u00e9<\/h1>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-d2f1b42d\">Cette d\u00e9claration de protection des donn\u00e9es d\u00e9crit comment nous traitons vos donn\u00e9es lorsque vous visitez notre site lumovape.fr - de la collecte \u00e0 l'enregistrement en passant par le traitement. Elle vous indique \u00e9galement quels sont vos droits en ce qui concerne vos donn\u00e9es personnelles et le cadre l\u00e9gal de protection dont elles b\u00e9n\u00e9ficient.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-fda3aaff\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-4204fedb\">Quelles donn\u00e9es collectons-nous ?<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-ee7fc6bb\">Pour le fonctionnement de notre boutique d'e-cigarettes, nous collectons diff\u00e9rents types d'informations :<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-3729ab10\">Donn\u00e9es personnelles<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-f1983f3a\">Les donn\u00e9es suivantes sont enregistr\u00e9es par nos soins :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pr\u00e9nom et nom de famille<\/li>\n\n\n\n<li>Adresse \u00e9lectronique<\/li>\n\n\n\n<li>Num\u00e9ro de t\u00e9l\u00e9phone<\/li>\n\n\n\n<li>Adresse d'exp\u00e9dition<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-ab92c44b\">Nous avons besoin de ces informations pour traiter les commandes, livrer les produits et vous aider \u00e0 r\u00e9pondre \u00e0 vos questions concernant vos achats.<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-c214233f\">Donn\u00e9es techniques d'utilisation<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-30585dd9\">Lorsque vous visitez notre site web, les informations suivantes sont automatiquement collect\u00e9es :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Type d'appareil<\/li>\n\n\n\n<li>Adresse IP<\/li>\n\n\n\n<li>Type de navigateur<\/li>\n\n\n\n<li>date et heure de l'acc\u00e8s<\/li>\n\n\n\n<li>Sous-pages visit\u00e9es<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-f9eb79a2\">Ces donn\u00e9es sont collect\u00e9es de mani\u00e8re techniquement automatis\u00e9e. Elles nous aident \u00e0 am\u00e9liorer l'exp\u00e9rience de l'utilisateur et \u00e0 respecter les exigences de s\u00e9curit\u00e9 et les r\u00e9glementations sp\u00e9cifiques au secteur de l'e-cigarette.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-91917e9b\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-c484e4a8\">Comment utilisons-nous vos donn\u00e9es ?<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-6078c16d\">Nous utilisons les informations collect\u00e9es aux fins suivantes :<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-bcdf351a\">Traitement des commandes<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-204a7188\">Vos donn\u00e9es personnelles sont utilis\u00e9es pour traiter les processus d'achat, coordonner l'exp\u00e9dition de vos articles et garantir un service apr\u00e8s-vente fiable.<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-4a65153a\">Communication avec les clients<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-c518f906\">Nous vous contactons au sujet de vos commandes, d'informations sur les produits ainsi que dans le cadre de mesures de marketing - y compris les modifications importantes et les informations relatives \u00e0 la s\u00e9curit\u00e9.<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-82378a03\">D\u00e9veloppement de notre offre<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-aa0740f3\">Gr\u00e2ce \u00e0 l'analyse des donn\u00e9es d'utilisation, nous am\u00e9liorons en permanence notre gamme de produits, les fonctions de notre site web et l'exp\u00e9rience d'achat en g\u00e9n\u00e9ral.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-386decb1\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-1d4885b5\">Transmission \u00e0 des tiers<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-7e5e7e2d\">En principe, vos donn\u00e9es personnelles ne sont pas transmises \u00e0 des organismes ext\u00e9rieurs sans votre consentement. Des exceptions s'appliquent dans les situations suivantes :<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-b481234e\">Prestataires de services mandat\u00e9s<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-ac5b0f2b\">Pour le traitement des livraisons et des paiements, nous transmettons les donn\u00e9es n\u00e9cessaires aux prestataires de services logistiques et de paiement ainsi qu'\u00e0 d'autres entreprises partenaires.<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-385ede52\">Exigences l\u00e9gales<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-7f728c24\">Si des obligations r\u00e9glementaires ou l\u00e9gales requi\u00e8rent une divulgation, nous nous y conformerons afin de respecter les lois et r\u00e9glementations en vigueur.<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-224c032c\">Changements dans l'entreprise<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-01790c42\">En cas de fusion, d'acquisition ou de vente d'une partie de l'entreprise, vos donn\u00e9es peuvent \u00eatre transf\u00e9r\u00e9es - elles restent dans tous les cas soumises aux dispositions de la pr\u00e9sente d\u00e9claration de confidentialit\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-b011cc10\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-58b0d237\">S\u00e9curit\u00e9 de vos donn\u00e9es<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-33b6d2af\">Pour prot\u00e9ger vos donn\u00e9es personnelles, nous utilisons diff\u00e9rentes mesures de s\u00e9curit\u00e9 techniques et organisationnelles, notamment des technologies de cryptage et des contr\u00f4les de s\u00e9curit\u00e9 r\u00e9guliers. Toutefois, nous ne pouvons pas garantir une s\u00e9curit\u00e9 totale lors de la transmission de donn\u00e9es par Internet.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-148da144\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-107dd16a\">Vos droits en tant que personne concern\u00e9e<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-b628d66f\">En tant qu'utilisateur, vous disposez des droits suivants :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Droit \u00e0 l'information :<\/strong> Vous pouvez demander \u00e0 consulter les donn\u00e9es enregistr\u00e9es \u00e0 votre sujet.<\/li>\n\n\n\n<li><strong>Droit de rectification :<\/strong> Vous pouvez faire corriger les informations inexactes ou incompl\u00e8tes.<\/li>\n\n\n\n<li><strong>Droit \u00e0 l'effacement :<\/strong> Vous avez le droit de demander la suppression de vos donn\u00e9es.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-2c8c1b47\">Si vous souhaitez faire effacer vos donn\u00e9es ou ne plus recevoir de communications marketing, vous pouvez nous contacter \u00e0 tout moment et en toute simplicit\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-4f1329d8\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-75a9a4f6\">Cookies et technologies de suivi<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-8b3a4f0a\">Nous utilisons des cookies et des technologies similaires pour am\u00e9liorer votre exp\u00e9rience sur notre site. Vous pouvez \u00e0 tout moment modifier les param\u00e8tres des cookies via votre navigateur. Veuillez noter que la d\u00e9sactivation des cookies peut limiter certaines fonctions du site web.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-d04919e9\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-ad7e237f\">Pas d'offre pour les mineurs<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-2aa4afdb\">Notre site web et nos produits s'adressent exclusivement aux personnes \u00e2g\u00e9es de 18 ans ou plus. Nous ne collectons sciemment aucune donn\u00e9e personnelle concernant des mineurs. Si de telles donn\u00e9es nous parvenaient par inadvertance, elles seraient supprim\u00e9es sans d\u00e9lai.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-bc241e84\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-e887e3e8\">Modifications de la pr\u00e9sente d\u00e9claration de confidentialit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-df54582a\">Nous nous r\u00e9servons le droit de r\u00e9viser la pr\u00e9sente d\u00e9claration de confidentialit\u00e9 si n\u00e9cessaire. Toute mise \u00e0 jour sera publi\u00e9e sur cette page et la date de la derni\u00e8re modification sera modifi\u00e9e en cons\u00e9quence. Nous vous recommandons de consulter cette page de temps en temps afin d'\u00eatre toujours inform\u00e9 de l'\u00e9tat actuel.<\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1604","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/pages\/1604","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/comments?post=1604"}],"version-history":[{"count":1,"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/pages\/1604\/revisions"}],"predecessor-version":[{"id":1605,"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/pages\/1604\/revisions\/1605"}],"wp:attachment":[{"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/media?parent=1604"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}