{"id":1607,"date":"2026-05-09T10:26:59","date_gmt":"2026-05-09T08:26:59","guid":{"rendered":"https:\/\/lumovape.de\/?page_id=1607"},"modified":"2026-05-09T10:33:37","modified_gmt":"2026-05-09T08:33:37","slug":"rueckgaberichtlinie","status":"publish","type":"page","link":"https:\/\/lumovape.de\/fr\/rueckgaberichtlinie\/","title":{"rendered":"Politique de retour"},"content":{"rendered":"<div class=\"wp-block-wd-divider wd-style-line wd-b81bb54b\"><\/div>\n\n\n\n<h1 class=\"wp-block-wd-title title wd-2c765100\">Politique de retour et de remboursement<\/h1>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-3c6ab1f6\">Veuillez lire attentivement les conditions de retour ci-dessous avant de nous contacter par e-mail pour un retour, un remboursement ou un \u00e9change.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-6d029871\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-6bbb63f6\">D\u00e9lais pour les retours et les \u00e9changes<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-20449c31\">Pr\u00e9voyez jusqu'\u00e0 3 jours pour la livraison de votre commande. La fen\u00eatre de retour est \u00e9galement de 3 jours \u00e0 compter de la date d'achat. Nous vous recommandons de v\u00e9rifier le bon fonctionnement de tous les articles d\u00e8s leur r\u00e9ception. Pass\u00e9 ce d\u00e9lai de 3 jours, aucun retour, remboursement ou \u00e9change - pour quelque raison que ce soit - ne sera accept\u00e9.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-110a8b33\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-8dc133a3\">Modifications et annulations de commandes<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-e4a97d2c\">Avant d'envoyer votre commande, v\u00e9rifiez que l'adresse de livraison indiqu\u00e9e est correcte. Si une correction est n\u00e9cessaire, vous pouvez demander une annulation ou une modification par e-mail \u00e0 arambulahalabymf487@gmail.com. Cependant, une fois que votre commande a \u00e9t\u00e9 exp\u00e9di\u00e9e, il n'est plus possible de l'annuler.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-2d74ca31\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-237959b1\">Colis non distribu\u00e9s<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-553a4e6f\">Si un client refuse le colis ou si la livraison \u00e9choue en raison d'une adresse erron\u00e9e, et qu'un remboursement est ensuite demand\u00e9, nous retenons 30 % du montant pay\u00e9 \u00e0 titre de frais de traitement.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-10154627\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-33ed3614\">Articles exclus du retour<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-cde38c13\">Les produits suivants ne peuvent en principe pas \u00eatre retourn\u00e9s :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>\u00c9chantillons gratuits ou cadeaux promotionnels<\/li>\n\n\n\n<li>Commandes sp\u00e9ciales par l'interm\u00e9diaire du personnel de vente - dans ce cas, veuillez vous adresser directement \u00e0 votre interlocuteur.<\/li>\n\n\n\n<li>Commandes en gros<\/li>\n\n\n\n<li>Articles standard d\u00e9j\u00e0 ouverts<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-6f27591b\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-924ab4f1\">Retours accept\u00e9s<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-8575387d\">Les retours ne sont accept\u00e9s que pour les produits dont il est prouv\u00e9 qu'ils sont d\u00e9fectueux. Aucun remboursement ne sera accord\u00e9 pour les produits qui fonctionnent. Veuillez ne pas renvoyer d'appareils ou d'articles en parfait \u00e9tat de marche. Des frais de restockage de 50 % s'appliquent aux articles ouverts et sans d\u00e9faut qui sont n\u00e9anmoins renvoy\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-a67befdf\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-892ee32b\">Produits non retournables<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-65027811\">Les articles suivants sont g\u00e9n\u00e9ralement exclus de l'\u00e9change et du retour :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Tous les produits ouverts ou manipul\u00e9s<\/li>\n\n\n\n<li>Pour des raisons d'hygi\u00e8ne et de s\u00e9curit\u00e9, les articles suivants ne sont pas repris :\n<ul class=\"wp-block-list\">\n<li>Huiles pour cigarettes \u00e9lectroniques \/ E-liquides<\/li>\n\n\n\n<li>Embouchures<\/li>\n\n\n\n<li>Cartouches<\/li>\n\n\n\n<li>Bobines<\/li>\n\n\n\n<li>R\u00e9servoirs ouverts \/ RDA \/ RDTA<\/li>\n\n\n\n<li>Noyaux d'\u00e9vaporation<\/li>\n\n\n\n<li>Fils<\/li>\n\n\n\n<li>Ouate<\/li>\n\n\n\n<li>R\u00e9servoirs<\/li>\n\n\n\n<li>\u00c9vaporateur<\/li>\n\n\n\n<li>T\u00eates d'\u00e9vaporation<\/li>\n\n\n\n<li>Piles<\/li>\n\n\n\n<li>Chargeurs<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-d637190c\">Les articles pr\u00e9sentant des dommages visibles, des d\u00e9g\u00e2ts des eaux ou des signes de manipulation sont \u00e9galement exclus des retours, des remboursements et des \u00e9changes.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-522b374f\">Nous d\u00e9clinons toute responsabilit\u00e9 en cas de d\u00e9coloration ou de d\u00e9faut d'emballage des e-liquides. L'utilisation s\u00fbre des produits rel\u00e8ve de votre propre responsabilit\u00e9 ; en les achetant, vous renoncez \u00e0 toutes les pr\u00e9tentions qui y sont li\u00e9es.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-645cf1f2\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-2f64a082\">D\u00e9roulement d'un retour<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-3a10133a\">Pour entamer une proc\u00e9dure de retour, notre service client\u00e8le se tient \u00e0 votre disposition par e-mail \u00e0 l'adresse arambulahalabymf487@gmail.com.<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-440e4074\">\u00c9tape 1 : Informations requises<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-396e351e\">Pour pouvoir traiter votre demande, nous avons besoin des informations suivantes :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Nom complet<\/li>\n\n\n\n<li>Num\u00e9ro de commande<\/li>\n\n\n\n<li>Date d'achat<\/li>\n\n\n\n<li>D\u00e9signation du produit \u00e0 renvoyer (marque, mod\u00e8le et, le cas \u00e9ch\u00e9ant, couleur)<\/li>\n\n\n\n<li>Raison du retour (par ex. produit d\u00e9fectueux, livraison erron\u00e9e)<\/li>\n\n\n\n<li>Preuve photo ou vid\u00e9o du d\u00e9faut - s'il vous pla\u00eet avec le code-barres visible, le num\u00e9ro de s\u00e9rie et le code QR sur l'emballage<\/li>\n\n\n\n<li>Solution souhait\u00e9e (par ex. remboursement, avoir ou \u00e9change)<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-1395fbde\"><em>Important : toute information incompl\u00e8te entra\u00eenera l'impossibilit\u00e9 de traiter le retour.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-064a9212\">\u00c9tape 2 : Retour et v\u00e9rification<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-86959cb1\">Apr\u00e8s r\u00e9ception de votre demande, il vous incombe d'emballer le produit en toute s\u00e9curit\u00e9 et de nous l'envoyer avec votre propre \u00e9tiquette d'exp\u00e9dition. Apr\u00e8s r\u00e9ception de la marchandise, nous avons besoin de 1 \u00e0 3 jours ouvrables pour contr\u00f4ler et traiter le retour.<\/p>\n\n\n\n<h3 class=\"wp-block-wd-title title wd-8559ebe7\">\u00c9tape 3 : Conditions pr\u00e9alables pour les articles d\u00e9fectueux<\/h3>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-7ce57ada\">Pour qu'un article d\u00e9fectueux puisse faire l'objet d'un \u00e9change ou d'un cr\u00e9dit, les conditions suivantes doivent \u00eatre remplies :<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Pas de dommages physiques visibles ni de rayures importantes<\/li>\n\n\n\n<li>Les d\u00e9fauts optiques mineurs, tels que de l\u00e9g\u00e8res rayures ou d\u00e9colorations, ne constituent pas un motif de retour.<\/li>\n\n\n\n<li>Tous les accessoires fournis doivent \u00eatre envoy\u00e9s avec l'appareil d\u00e9fectueux.<\/li>\n\n\n\n<li>L'emballage du colis de retour doit \u00eatre effectu\u00e9 avec soin - en cas de dommages de transport dus \u00e0 un emballage insuffisant, un cr\u00e9dit complet ne peut pas \u00eatre accord\u00e9. Si le dommage est clairement imputable au prestataire de services d'exp\u00e9dition et que la marchandise \u00e9tait correctement emball\u00e9e, vous n'en \u00eates pas responsable.<\/li>\n\n\n\n<li>L'article ne doit pas faire partie des produits non retournables<\/li>\n<\/ul>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-b833342b\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-d23a541b\">Remboursements et \u00e9changes<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-47a68480\">Une fois la v\u00e9rification termin\u00e9e, nous proc\u00e9dons au remboursement ou \u00e0 l'\u00e9change conform\u00e9ment \u00e0 votre demande. Si vous souhaitez que votre paiement soit recr\u00e9dit\u00e9 sur votre mode de paiement initial (par exemple, carte de cr\u00e9dit), veuillez nous en informer par e-mail. Pour les retours envoy\u00e9s par la poste, le traitement s'effectue dans un d\u00e9lai de 7 \u00e0 10 jours ouvrables apr\u00e8s r\u00e9ception de la marchandise. Selon le temps de traitement de votre banque, cela peut prendre jusqu'\u00e0 10 jours suppl\u00e9mentaires pour que le montant apparaisse sur votre compte. Pour les demandes d'\u00e9change, contactez-nous \u00e9galement par e-mail.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-02735c1b\"><em>Remarque : les frais d'envoi ne sont en principe pas rembours\u00e9s.<\/em><\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-435b943b\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-29cb54c6\">Proc\u00e9dure de remboursement<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-17a3cbdb\">Une fois que nous aurons re\u00e7u et v\u00e9rifi\u00e9 votre retour, vous recevrez un e-mail de confirmation de la r\u00e9ception des marchandises et une notification indiquant si votre remboursement a \u00e9t\u00e9 approuv\u00e9 ou refus\u00e9. En cas d'approbation, le remboursement sera effectu\u00e9 dans un d\u00e9lai de 3 \u00e0 7 jours ouvrables sur votre carte de cr\u00e9dit ou le mode de paiement utilis\u00e9 \u00e0 l'origine.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-59448444\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-ee8418ed\">Prix promotionnels et prix de vente<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-ff26c2c5\">Les remboursements ne sont possibles que pour les articles au prix de vente normal ; les articles en promotion \u00e0 prix r\u00e9duit ne peuvent pas \u00eatre retourn\u00e9s. En cas d'\u00e9change de produits sold\u00e9s, nous ne pouvons pas garantir que l'article en question soit encore disponible, car les articles en promotion ne sont pas r\u00e9approvisionn\u00e9s. Si un article n'est plus disponible au moment du traitement de l'\u00e9change, nous vous contacterons pour trouver ensemble une solution alternative.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-e9f9e4b1\"><strong>Remarque :<\/strong> Nous d\u00e9clinons toute responsabilit\u00e9 pour les colis perdus, vol\u00e9s ou endommag\u00e9s sur le chemin du retour. Si, lors du traitement, nous constatons qu'un colis est endommag\u00e9, qu'il manque des articles ou qu'il ne s'agit pas de nos produits, nous vous en informerons dans les 24 \u00e0 48 heures.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-7658be3b\">Si un retour soumis ne correspond pas aux conditions de retour et que vous souhaitez que l'article soit renvoy\u00e9, les frais d'envoi occasionn\u00e9s sont \u00e0 votre charge. Les articles qui ne peuvent pas \u00eatre retourn\u00e9s ne le seront qu'apr\u00e8s le paiement des frais d'exp\u00e9dition. Avant de renvoyer un article, veuillez v\u00e9rifier soigneusement si votre produit remplit les conditions requises - en cas de doute, contactez-nous avant de renvoyer l'article.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-96dd8216\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-477f522e\">Restitution par repentir<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-081dcf3b\">Les retours d'articles ouverts ou d\u00e9j\u00e0 utilis\u00e9s, qui ne pr\u00e9sentent pas de d\u00e9fauts techniques, ne sont en principe pas accept\u00e9s.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-67434cbd\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-bb8831d5\">Informations juridiques sur l'envoi<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-cfa7f3ee\">Avant d'acheter des produits sur lumovape.fr, veuillez vous renseigner sur les dispositions l\u00e9gales en vigueur dans votre r\u00e9gion. lumovape n'assume aucune responsabilit\u00e9 pour les \u00e9ventuelles infractions l\u00e9gales qui pourraient r\u00e9sulter de l'achat ou de l'utilisation de nos produits.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-61660c22\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-51168377\">Contre remboursement<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-5bdc0be8\">Nous ne proposons pas l'envoi contre remboursement.<\/p>\n\n\n\n<div class=\"wp-block-wd-divider wd-style-line wd-d1ad7d60\"><\/div>\n\n\n\n<h2 class=\"wp-block-wd-title title wd-b8beecaf\">Clause de non-responsabilit\u00e9<\/h2>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-223e3a1d\">lumovape ne fournit pas de conseils juridiques. Toutes les informations, tous les contenus et tous les mat\u00e9riels mis \u00e0 disposition sur ce site Internet servent uniquement \u00e0 des fins d'information g\u00e9n\u00e9rale et ne pr\u00e9tendent pas \u00eatre \u00e0 jour d'un point de vue juridique ou autre.<\/p>\n\n\n\n<p class=\"wp-block-wd-paragraph wd-5b172838\">lumovape n'est pas responsable des blessures, dommages ou d\u00e9fauts - qu'ils soient permanents ou temporaires - caus\u00e9s par une mauvaise utilisation des piles au lithium-ion. Veuillez vous procurer des connaissances suffisantes sur la manipulation des piles que vous utilisez et les utiliser toujours avec pr\u00e9caution.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1607","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/pages\/1607","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/comments?post=1607"}],"version-history":[{"count":2,"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/pages\/1607\/revisions"}],"predecessor-version":[{"id":1614,"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/pages\/1607\/revisions\/1614"}],"wp:attachment":[{"href":"https:\/\/lumovape.de\/fr\/wp-json\/wp\/v2\/media?parent=1607"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}